{"id":541,"date":"2024-04-05T21:38:29","date_gmt":"2024-04-05T19:38:29","guid":{"rendered":"https:\/\/www.uif.gob.bo\/?page_id=541"},"modified":"2024-04-05T23:04:55","modified_gmt":"2024-04-05T21:04:55","slug":"presupuesto-aprobado-por-unidad-organizacional","status":"publish","type":"page","link":"https:\/\/www.uif.gob.bo\/index.php\/presupuesto-aprobado-por-unidad-organizacional\/","title":{"rendered":"Presupuesto aprobado por unidad organizacional"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-541","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/pages\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":1,"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/pages\/541\/revisions"}],"predecessor-version":[{"id":1027,"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/pages\/541\/revisions\/1027"}],"wp:attachment":[{"href":"https:\/\/www.uif.gob.bo\/index.php\/wp-json\/wp\/v2\/media?parent=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}